{"id":16838,"date":"2024-06-18T00:56:44","date_gmt":"2024-06-18T03:56:44","guid":{"rendered":"https:\/\/ava.inovensa.com.br\/?page_id=16838"},"modified":"2024-07-30T12:49:06","modified_gmt":"2024-07-30T15:49:06","slug":"semana-da-radioprotecao-na-medicina","status":"publish","type":"page","link":"https:\/\/ava.inovensa.com.br\/en\/semana-da-radioprotecao-na-medicina\/","title":{"rendered":"Chamada a A\u00e7\u00e3o para Radioprote\u00e7\u00e3o na Medicina"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"16838\" class=\"elementor elementor-16838\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6685f48 e-flex e-con-boxed e-con e-parent\" data-id=\"6685f48\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5ef49c1 e-flex e-con-boxed e-con e-parent\" data-id=\"5ef49c1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f9da533 e-con-full e-flex e-con e-child\" data-id=\"f9da533\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a40ab37 elementor-widget elementor-widget-heading\" data-id=\"a40ab37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Participe do Movimento pela Seguran\u00e7a Radiol\u00f3gica na Medicina!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2275165 elementor-widget elementor-widget-text-editor\" data-id=\"2275165\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5 style=\"text-align: center;\"><span style=\"color: #000000;\">Bem-vindo \u00e0 Campanha em prol de Maximizarmos a Seguran\u00e7a Radiol\u00f3gica na Medicina!<\/span><\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42656e4 elementor-widget elementor-widget-text-editor\" data-id=\"42656e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6>Sobre<strong> a Campanha<\/strong><\/h6>\n<p>A campanha \u00e9 uma chamada a a\u00e7\u00e3o para potencializarmos os beneficios da radioprote\u00e7\u00e3o para profissionais, pacientes e para o p\u00fablico em geral. Esta iniciativa da Inovensa tem como objetivo aumentar a conscientiza\u00e7\u00e3o radiol\u00f3gica e promover a radioprote\u00e7\u00e3o para um ambiente m\u00e9dico mais seguro.&nbsp;<\/p>\n<p>Assim, como na campanha de vacina\u00e7\u00e3o, estaremos entregando conhecimento em pequenas doses, esperamos, que em um curto per\u00edodo de tempo poderemos:<\/p>\n<ul>\n<li>Usufruir de ambientes mais seguros e protegidos.&nbsp;<\/li>\n<li>Gerar a conscientiza\u00e7\u00e3o e o respeito necess\u00e1rio para todos os profissionais atuarem com <span style=\"text-align: var(--text-align); color: var(--body-text-color); font-family: var(--body-font); font-size: var(--body-font-size); font-weight: var(--body-font-weight); text-transform: var(--body-text-transform);\">as radia\u00e7\u00f5es ionizantes.<\/span><\/li>\n<li><span style=\"text-align: var(--text-align); color: var(--body-text-color); font-family: var(--body-font); font-size: var(--body-font-size); font-weight: var(--body-font-weight); text-transform: var(--body-text-transform);\">Entregar conhecimentos sobre a radiobiologia e os potenciais&nbsp;<\/span><span style=\"text-align: var(--text-align); color: var(--body-text-color); font-family: var(--body-font); font-size: var(--body-font-size); font-weight: var(--body-font-weight); text-transform: var(--body-text-transform);\">impactos que os efeitos indesejados das radia\u00e7\u00f5es ionizantes promovem e como auxiliar pacientes e profissionais afetados.&nbsp;<\/span><\/li>\n<li><span style=\"text-align: var(--text-align); color: var(--body-text-color); font-family: var(--body-font); font-size: var(--body-font-size); font-weight: var(--body-font-weight); text-transform: var(--body-text-transform);\">Entre outros t\u00f3picos que estaremos abordando durante essa campanha.<\/span><\/li>\n<\/ul>\n<p><span style=\"text-align: var(--text-align); color: var(--body-text-color); font-family: var(--body-font); font-size: var(--body-font-size); font-weight: var(--body-font-weight); text-transform: var(--body-text-transform);\">Acreditem! A radioprote\u00e7\u00e3o sempre ser\u00e1 necess\u00e1ria em ambientes com exposi\u00e7\u00e3o as radia\u00e7\u00f5es ionizantes. O&nbsp;<\/span><span style=\"text-align: var(--text-align); color: var(--body-text-color); font-family: var(--body-font); font-size: var(--body-font-size); font-weight: var(--body-font-weight); text-transform: var(--body-text-transform);\">grande desafio da radioprote\u00e7\u00e3o se deve pelas radia\u00e7\u00f5es ionizantes n\u00e3o terem cheiro e nem cor, levando os profissionais a esquecerem que trabalham em ambientes controlados.&nbsp;<\/span><\/p>\n<p>Nossa preocupa\u00e7\u00e3o decorre do fato de que o conhecimento sobre radioprote\u00e7\u00e3o, atualmente, \u00e9 predominantemente restrito a f\u00edsicos, f\u00edsicos m\u00e9dicos, m\u00e9dicos radiologistas, tecn\u00f3logos e t\u00e9cnicos de radiologia, al\u00e9m de alguns poucos que buscaram adquirir esse conhecimento. Essa realidade faz com que uma parte significativa do saber, especialmente em \u00e1reas como a f\u00edsica e a f\u00edsica m\u00e9dica, esteja retida apenas entre esses profissionais especializados.<span style=\"text-align: var(--text-align); color: var(--body-text-color); font-family: var(--body-font); font-size: var(--body-font-size); font-weight: var(--body-font-weight); text-transform: var(--body-text-transform);\"><br><\/span><\/p>\n<p><span style=\"text-align: var(--text-align); color: var(--body-text-color); font-family: var(--body-font); font-size: var(--body-font-size); font-weight: var(--body-font-weight); text-transform: var(--body-text-transform);\">&nbsp;<\/span><\/p>\n<p><\/p>\n<p><span style=\"text-align: var(--text-align); color: var(--body-text-color); font-family: var(--body-font); font-size: var(--body-font-size); font-weight: var(--body-font-weight); text-transform: var(--body-text-transform);\">&nbsp;<\/span><\/p>\n<p><span style=\"color: var(--body-text-color); font-family: var(--body-font); font-size: var(--body-font-size); font-weight: var(--body-font-weight); text-align: var(--text-align); text-transform: var(--body-text-transform);\">&nbsp;<\/span><\/p>\n<p><span style=\"text-align: var(--text-align); color: var(--body-text-color); font-family: var(--body-font); font-size: var(--body-font-size); font-weight: var(--body-font-weight); text-transform: var(--body-text-transform);\">&nbsp;<\/span><\/p>\n<p><span style=\"text-align: var(--text-align); color: var(--body-text-color); font-family: var(--body-font); font-size: var(--body-font-size); font-weight: var(--body-font-weight); text-transform: var(--body-text-transform);\">que&nbsp;<\/span><span style=\"color: var(--body-text-color); font-family: var(--body-font); font-size: var(--body-font-size); font-weight: var(--body-font-weight); text-align: var(--text-align); text-transform: var(--body-text-transform);\">utilizadas com respeito que n\u00e3o s\u00e3o da radiologia e atuam nessa \u00e1rea conhecendo e reconhecendo o que precisa ser melhorado na seguran\u00e7a radiol\u00f3gica, para si pr\u00f3prio, para os demais individuos que precisam trabalhar em ambientes com radia\u00e7\u00e3o ioizante e para os pacientes que muitas vezes ficam com medo e n\u00e3o&nbsp;<\/span><\/p>\n<p>pr\u00e1ticas seguras de radioprote\u00e7\u00e3o. Esta campanha \u00e9 aberta a todos os profissionais de sa\u00fade e ao p\u00fablico em geral que desejam fazer a diferen\u00e7a na seguran\u00e7a radiol\u00f3gica. Os participantes t\u00eam a oportunidade de enviar v\u00eddeos educativos e compartilhar suas d\u00favidas e conhecimentos sobre radioprote\u00e7\u00e3o.&#8221;<\/p>\n<p>&nbsp;Envie seu v\u00eddeo, compartilhe suas ideias e ajude a promover a radioprote\u00e7\u00e3o na medicina.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ac6a1e elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"2ac6a1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/ava.inovensa.com.br\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png);\" role=\"img\" aria-label=\"\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tIsto \u00e9 o t\u00edtulo\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tLorem ipsum dolor sit amet consectetur adipiscing elit dolor\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\">\n\t\t\t\t\t\tClique aqui\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Participe do Movimento pela Seguran\u00e7a Radiol\u00f3gica na Medicina! Bem-vindo \u00e0 Campanha em prol de Maximizarmos a Seguran\u00e7a Radiol\u00f3gica na Medicina!<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"qubely_global_settings":"","qubely_interactions":"","_tutorstarter_page_metadata":[],"footnotes":""},"class_list":["post-16838","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/ava.inovensa.com.br\/en\/wp-json\/wp\/v2\/pages\/16838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ava.inovensa.com.br\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ava.inovensa.com.br\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ava.inovensa.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ava.inovensa.com.br\/en\/wp-json\/wp\/v2\/comments?post=16838"}],"version-history":[{"count":18,"href":"https:\/\/ava.inovensa.com.br\/en\/wp-json\/wp\/v2\/pages\/16838\/revisions"}],"predecessor-version":[{"id":17313,"href":"https:\/\/ava.inovensa.com.br\/en\/wp-json\/wp\/v2\/pages\/16838\/revisions\/17313"}],"wp:attachment":[{"href":"https:\/\/ava.inovensa.com.br\/en\/wp-json\/wp\/v2\/media?parent=16838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}